{"id":100003264,"date":"2020-11-12T08:34:59","date_gmt":"2020-11-12T07:34:59","guid":{"rendered":"https:\/\/swissholdings.ch\/fr\/was-aendert-die-uvi-auf-den-kakaoplantagen-in-westafrika-12\/"},"modified":"2020-11-12T08:34:59","modified_gmt":"2020-11-12T07:34:59","slug":"was-aendert-die-uvi-auf-den-kakaoplantagen-in-westafrika-12","status":"publish","type":"post","link":"https:\/\/swissholdings.ch\/fr\/was-aendert-die-uvi-auf-den-kakaoplantagen-in-westafrika-12\/","title":{"rendered":"Was \u00e4ndert die UVI auf den Kakaoplantagen in Westafrika?"},"content":{"rendered":"<div id=\"ftn3\">\n<div id=\"ftn4\">\n<p><strong>Sorgfaltspflichten, Beweislastumkehr, Haftungsnormen \u2013 \u00fcber die Unternehmens-Verantwortungs-Initiative wird viel diskutiert. Was w\u00fcrde sich aber konkret f\u00fcr betroffene Schweizer Unternehmen nach einer Annahme der Initiative \u00e4ndern? Wir haben nachgefragt. Nestl\u00e9 gibt einen Einblick in die Herausforderungen rund um Kinderarbeit entlang ihrer Kakaolieferkette in der Elfenbeink\u00fcste und Ghana.<\/strong><\/p>\n<p>72 Prozent der weltweiten Kakaoproduktion konzentriert sich auf Westafrika. Nestl\u00e9 bezieht einen grossen Teil des Kakaos aus der Elfenbeink\u00fcste und Ghana. Im Bereich der Kakaoproduktion arbeitet Nestl\u00e9 direkt mit Kleinbauern zusammen, obschon das Unternehmen etwa 97 Prozent des Kakaos von Rohwarenh\u00e4ndlern bezieht. Viele der Kleinbauern betreiben ihre Farmen weit abseits von St\u00e4dten und befestigten Strassen. Die Situation vor Ort unterscheidet sich fundamental von derjenigen in der Schweiz. Kinderarbeit ist leider nach wie vor \u00fcblich. Die Gr\u00fcnde daf\u00fcr sind vielf\u00e4ltig und erstrecken sich von der grossen Armut und damit der Notwendigkeit, dass sich Kinder am Familieneinkommen beteiligen, \u00fcber die illegale Einwanderung von Kindern bis hin zu fehlenden Geburtsurkunden und dadurch dem Ausschluss von der Sekundarschule.<\/p>\n<p>&nbsp;<\/p>\n<div><strong>Was geschieht aktuell?<\/strong><br \/>\nNestl\u00e9 ist sich der Probleme bewusst und arbeitet daran, die Situation zu verbessern. Zu diesem Zweck werden Familien besucht und Kinder identifiziert, die schwere und teils gef\u00e4hrliche Arbeiten verrichten. Im Anschluss wird das Gespr\u00e4ch gesucht, um den Eltern zu erkl\u00e4ren, warum die Kinder nicht arbeiten d\u00fcrfen.\u00a0Um sicherzustellen, dass die Kinder nicht anderweitig arbeiten, reicht es jedoch nicht aus, ihnen die Arbeit auf der Plantage zu verbieten.Es bedarf einer Alternative, namentlich der M\u00f6glichkeit nach Bildung. Dazu wird je nach Situation eine Kombination von Massnahmen implementiert: Die Beschaffung von fehlenden Geburtsurkunden als Voraussetzung des Schulbesuchs;\u00a0der Bau von Schulen in abgelegenen Regionen;\u00a0der Kauf von Schulmaterial oder Br\u00fcckenangebote f\u00fcr Kinder, die Jahre an Schulbildung verpasst haben. Anschliessend wird die Situation regelm\u00e4ssig \u00fcberpr\u00fcft und der Erfolg gemessen.Das Resultat: In vergangenen Jahren konnten bereits rund 10&#8217;000 Kindern von der Arbeit auf Plantagen befreit werden. Es bleibt aber noch viel zu tun.<\/p>\n<p>&nbsp;<\/p>\n<div><strong>Welchen Effekt h\u00e4tte die Annahme der Initiative?<\/strong><br \/>\nNach einem Ja zur Unternehmens-Verantwortungs-Initiative am 29. November 2020 w\u00fcrde jedes Kind auf einer Kakaoplantage, die f\u00fcr Nestl\u00e9 produziert, zu einem Haftungsrisiko. Die transparente Berichterstattung k\u00f6nnte jederzeit vor Gericht gegen Nestl\u00e9 verwendet werden.Die Zusammenarbeit insbesondere mit kleineren Produzenten, wo man Probleme identifiziert hat oder vermutet, wird riskant. Stattdessen w\u00fcrde die Zusammenarbeit mit grossen Lieferanten, die sich mit Zertifikaten ausstatten, attraktiver. Gewissen Lieferanten droht somit insbesondere in risikoreichen Regionen das Ausscheiden aus den Lieferketten von Nestl\u00e9. Die Bauern riskieren, den Anschluss an die M\u00e4rkte zu verlieren. Ihre Einkommensverh\u00e4ltnisse und Lebensbedingungen werden sich nicht verbessern und an der Armut als einer der Urspr\u00fcnge von Kinderarbeit, \u00e4ndert sich wenig. Stattdessen m\u00fcsste in der Schweiz eine umfassende B\u00fcrokratie aufgebaut und zus\u00e4tzliche Juristen eingestellt werden, um die Haftungsrisiken zu minimieren.<\/div>\n<div><\/div>\n<div>Egal wie man es dreht und wendet: Geholfen w\u00e4re damit in der Praxis niemandem.&nbsp;<\/p>\n<div><em><strong>&#8220;Die Unternehmens-Verantwortungs-Initiative erkl\u00e4rt&#8221;<\/strong><\/em><\/div>\n<div><em>Eine umfassende Beschreibung der Forderungen der Initiative und unser komplettes Argumentarium finden Sie hier: <a href=\"https:\/\/swissholdings.ch\/dossier-uvi\/\" data-cke-saved-href=\"https:\/\/swissholdings.ch\/dossier-uvi\/\">https:\/\/swissholdings.ch\/dossier-uvi\/<\/a><\/em><\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Sorgfaltspflichten, Beweislastumkehr, Haftungsnormen \u2013 \u00fcber die Unternehmens-Verantwortungs-Initiative wird viel diskutiert. Was w\u00fcrde sich aber konkret f\u00fcr betroffene Schweizer Unternehmen nach einer Annahme der Initiative \u00e4ndern? Wir haben nachgefragt. Nestl\u00e9 gibt einen Einblick in die Herausforderungen rund um Kinderarbeit entlang ihrer Kakaolieferkette in der Elfenbeink\u00fcste und Ghana. 72 Prozent der weltweiten Kakaoproduktion konzentriert sich auf Westafrika. &hellip;<\/p>\n","protected":false},"author":4,"featured_media":100003100,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[54,51],"tags":[],"class_list":["post-100003264","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-konzern-initiative","category-editorials"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Was \u00e4ndert die UVI auf den Kakaoplantagen in Westafrika? - %<\/title>\n<meta name=\"description\" content=\"Was w\u00fcrde sich aber konkret f\u00fcr betroffene Schweizer Unternehmen nach einer Annahme der Initiative \u00e4ndern? Wir haben nachgefragt.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/swissholdings.ch\/fr\/was-aendert-die-uvi-auf-den-kakaoplantagen-in-westafrika-12\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Was \u00e4ndert die UVI auf den Kakaoplantagen in Westafrika? - %\" \/>\n<meta property=\"og:description\" content=\"Was w\u00fcrde sich aber konkret f\u00fcr betroffene Schweizer Unternehmen nach einer Annahme der Initiative \u00e4ndern? Wir haben nachgefragt.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/swissholdings.ch\/fr\/was-aendert-die-uvi-auf-den-kakaoplantagen-in-westafrika-12\/\" \/>\n<meta property=\"og:site_name\" content=\"Swissholdings FR\" \/>\n<meta property=\"article:published_time\" content=\"2020-11-12T07:34:59+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/swissholdings.ch\/fr\/wp-content\/uploads\/sites\/3\/2020\/07\/Direktinvestitionen-2.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1\" \/>\n\t<meta property=\"og:image:height\" content=\"1\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Pascal Nussbaum\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Pascal Nussbaum\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/swissholdings.ch\/fr\/was-aendert-die-uvi-auf-den-kakaoplantagen-in-westafrika-12\/\",\"url\":\"https:\/\/swissholdings.ch\/fr\/was-aendert-die-uvi-auf-den-kakaoplantagen-in-westafrika-12\/\",\"name\":\"Was \u00e4ndert die UVI auf den Kakaoplantagen in Westafrika? - %\",\"isPartOf\":{\"@id\":\"https:\/\/swissholdings.ch\/fr\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/swissholdings.ch\/fr\/was-aendert-die-uvi-auf-den-kakaoplantagen-in-westafrika-12\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/swissholdings.ch\/fr\/was-aendert-die-uvi-auf-den-kakaoplantagen-in-westafrika-12\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/swissholdings.ch\/fr\/wp-content\/uploads\/sites\/3\/2020\/07\/Direktinvestitionen-2.jpg\",\"datePublished\":\"2020-11-12T07:34:59+00:00\",\"author\":{\"@id\":\"https:\/\/swissholdings.ch\/fr\/#\/schema\/person\/f9ff363c9d3fafcfac26fa22fef45743\"},\"description\":\"Was w\u00fcrde sich aber konkret f\u00fcr betroffene Schweizer Unternehmen nach einer Annahme der Initiative \u00e4ndern? Wir haben nachgefragt.\",\"breadcrumb\":{\"@id\":\"https:\/\/swissholdings.ch\/fr\/was-aendert-die-uvi-auf-den-kakaoplantagen-in-westafrika-12\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/swissholdings.ch\/fr\/was-aendert-die-uvi-auf-den-kakaoplantagen-in-westafrika-12\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/swissholdings.ch\/fr\/was-aendert-die-uvi-auf-den-kakaoplantagen-in-westafrika-12\/#primaryimage\",\"url\":\"https:\/\/swissholdings.ch\/fr\/wp-content\/uploads\/sites\/3\/2020\/07\/Direktinvestitionen-2.jpg\",\"contentUrl\":\"https:\/\/swissholdings.ch\/fr\/wp-content\/uploads\/sites\/3\/2020\/07\/Direktinvestitionen-2.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/swissholdings.ch\/fr\/was-aendert-die-uvi-auf-den-kakaoplantagen-in-westafrika-12\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/swissholdings.ch\/fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Was \u00e4ndert die UVI auf den Kakaoplantagen in Westafrika?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/swissholdings.ch\/fr\/#website\",\"url\":\"https:\/\/swissholdings.ch\/fr\/\",\"name\":\"Swissholdings FR\",\"description\":\"Swissholdings\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/swissholdings.ch\/fr\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/swissholdings.ch\/fr\/#\/schema\/person\/f9ff363c9d3fafcfac26fa22fef45743\",\"name\":\"Pascal Nussbaum\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/swissholdings.ch\/fr\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/664120f276d22cf6fb7f7fd5f48b7b96?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/664120f276d22cf6fb7f7fd5f48b7b96?s=96&d=mm&r=g\",\"caption\":\"Pascal Nussbaum\"},\"url\":\"https:\/\/swissholdings.ch\/fr\/author\/nussbaum\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Was \u00e4ndert die UVI auf den Kakaoplantagen in Westafrika? - %","description":"Was w\u00fcrde sich aber konkret f\u00fcr betroffene Schweizer Unternehmen nach einer Annahme der Initiative \u00e4ndern? Wir haben nachgefragt.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/swissholdings.ch\/fr\/was-aendert-die-uvi-auf-den-kakaoplantagen-in-westafrika-12\/","og_locale":"fr_FR","og_type":"article","og_title":"Was \u00e4ndert die UVI auf den Kakaoplantagen in Westafrika? - %","og_description":"Was w\u00fcrde sich aber konkret f\u00fcr betroffene Schweizer Unternehmen nach einer Annahme der Initiative \u00e4ndern? Wir haben nachgefragt.","og_url":"https:\/\/swissholdings.ch\/fr\/was-aendert-die-uvi-auf-den-kakaoplantagen-in-westafrika-12\/","og_site_name":"Swissholdings FR","article_published_time":"2020-11-12T07:34:59+00:00","og_image":[{"url":"https:\/\/swissholdings.ch\/fr\/wp-content\/uploads\/sites\/3\/2020\/07\/Direktinvestitionen-2.jpg","width":1,"height":1,"type":"image\/jpeg"}],"author":"Pascal Nussbaum","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Pascal Nussbaum","Dur\u00e9e de lecture estim\u00e9e":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/swissholdings.ch\/fr\/was-aendert-die-uvi-auf-den-kakaoplantagen-in-westafrika-12\/","url":"https:\/\/swissholdings.ch\/fr\/was-aendert-die-uvi-auf-den-kakaoplantagen-in-westafrika-12\/","name":"Was \u00e4ndert die UVI auf den Kakaoplantagen in Westafrika? - %","isPartOf":{"@id":"https:\/\/swissholdings.ch\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/swissholdings.ch\/fr\/was-aendert-die-uvi-auf-den-kakaoplantagen-in-westafrika-12\/#primaryimage"},"image":{"@id":"https:\/\/swissholdings.ch\/fr\/was-aendert-die-uvi-auf-den-kakaoplantagen-in-westafrika-12\/#primaryimage"},"thumbnailUrl":"https:\/\/swissholdings.ch\/fr\/wp-content\/uploads\/sites\/3\/2020\/07\/Direktinvestitionen-2.jpg","datePublished":"2020-11-12T07:34:59+00:00","author":{"@id":"https:\/\/swissholdings.ch\/fr\/#\/schema\/person\/f9ff363c9d3fafcfac26fa22fef45743"},"description":"Was w\u00fcrde sich aber konkret f\u00fcr betroffene Schweizer Unternehmen nach einer Annahme der Initiative \u00e4ndern? Wir haben nachgefragt.","breadcrumb":{"@id":"https:\/\/swissholdings.ch\/fr\/was-aendert-die-uvi-auf-den-kakaoplantagen-in-westafrika-12\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/swissholdings.ch\/fr\/was-aendert-die-uvi-auf-den-kakaoplantagen-in-westafrika-12\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/swissholdings.ch\/fr\/was-aendert-die-uvi-auf-den-kakaoplantagen-in-westafrika-12\/#primaryimage","url":"https:\/\/swissholdings.ch\/fr\/wp-content\/uploads\/sites\/3\/2020\/07\/Direktinvestitionen-2.jpg","contentUrl":"https:\/\/swissholdings.ch\/fr\/wp-content\/uploads\/sites\/3\/2020\/07\/Direktinvestitionen-2.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/swissholdings.ch\/fr\/was-aendert-die-uvi-auf-den-kakaoplantagen-in-westafrika-12\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/swissholdings.ch\/fr\/"},{"@type":"ListItem","position":2,"name":"Was \u00e4ndert die UVI auf den Kakaoplantagen in Westafrika?"}]},{"@type":"WebSite","@id":"https:\/\/swissholdings.ch\/fr\/#website","url":"https:\/\/swissholdings.ch\/fr\/","name":"Swissholdings FR","description":"Swissholdings","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/swissholdings.ch\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/swissholdings.ch\/fr\/#\/schema\/person\/f9ff363c9d3fafcfac26fa22fef45743","name":"Pascal Nussbaum","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/swissholdings.ch\/fr\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/664120f276d22cf6fb7f7fd5f48b7b96?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/664120f276d22cf6fb7f7fd5f48b7b96?s=96&d=mm&r=g","caption":"Pascal Nussbaum"},"url":"https:\/\/swissholdings.ch\/fr\/author\/nussbaum\/"}]}},"_links":{"self":[{"href":"https:\/\/swissholdings.ch\/fr\/wp-json\/wp\/v2\/posts\/100003264","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/swissholdings.ch\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/swissholdings.ch\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/swissholdings.ch\/fr\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/swissholdings.ch\/fr\/wp-json\/wp\/v2\/comments?post=100003264"}],"version-history":[{"count":0,"href":"https:\/\/swissholdings.ch\/fr\/wp-json\/wp\/v2\/posts\/100003264\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/swissholdings.ch\/fr\/wp-json\/wp\/v2\/media\/100003100"}],"wp:attachment":[{"href":"https:\/\/swissholdings.ch\/fr\/wp-json\/wp\/v2\/media?parent=100003264"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/swissholdings.ch\/fr\/wp-json\/wp\/v2\/categories?post=100003264"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/swissholdings.ch\/fr\/wp-json\/wp\/v2\/tags?post=100003264"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}