{"id":100002456,"date":"2021-02-04T10:12:34","date_gmt":"2021-02-04T09:12:34","guid":{"rendered":"https:\/\/swissholdings.ch\/en\/swissholdings-begruesst-expertenbericht-steuerstandort-schweiz-4\/"},"modified":"2021-02-04T10:12:34","modified_gmt":"2021-02-04T09:12:34","slug":"swissholdings-begruesst-expertenbericht-steuerstandort-schweiz-4","status":"publish","type":"post","link":"https:\/\/swissholdings.ch\/en\/swissholdings-begruesst-expertenbericht-steuerstandort-schweiz-4\/","title":{"rendered":"SwissHoldings begr\u00fcsst Expertenbericht Steuerstandort Schweiz"},"content":{"rendered":"<p><strong>Die politische Debatte wird aktuell von den Auswirkungen der Corona-Pandemie bzw. von den zu deren Eind\u00e4mmung ergriffenen Massnahmen dominiert. Dieser Fokus ist richtig. Dennoch muss die Schweiz den Blick bereits heute wieder nach vorne richten. Steuerreformen, die unseren Wirtschafsstandort st\u00e4rken, haben angesichts der konjunkturellen Lage und der Schuldensituation noch einmal an Bedeutung und Dringlichkeit gewonnen. <\/strong><\/p>\n<p>Das Eidgen\u00f6ssische Finanzdepartement ver\u00f6ffentlichte heute seinen <a href=\"https:\/\/www.newsd.admin.ch\/newsd\/message\/attachments\/65178.pdf\">Expertenbericht zum Steuerstandort Schweiz<\/a>. Der Bericht beinhaltet eine Gesamtschau von Reformen, die positive volkswirtschaftliche Impulse bewirken und geeignet sind, mittel- bis l\u00e4ngerfristig die Wohlfahrt der Schweiz zu steigern. Angesichts der angespannten wirtschaftlichen und finanzpolitischen Lage erscheint es umso dringender, die steuerpolitische Debatte auf Massnahmen zu konzentrieren, die ein g\u00fcnstiges Kosten-Nutzen-Verh\u00e4ltnis aufweisen und die Schweiz als attraktiven Investitionsstandort st\u00e4rken. Insbesondere wird empfohlen, die Verrechnungssteuer zu reformieren, den Beteiligungsabzug zu optimieren sowie den Abbau von Transaktionssteuern (z.B. Emissionsabgabe) an die Hand zu nehmen. SwissHoldings unterst\u00fctzt zahlreiche Massnahmen klar.<\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<p><strong>Notwendige Verbesserungen des Steuersystems<\/strong><\/p>\n<p>Die Expertengruppe empfiehlt, die <strong>Verrechnungssteuer<\/strong> zu reformieren, wodurch der Fremdkapitalmarkt der Schweiz und der Schweizer Konzerne gest\u00e4rkt w\u00fcrde. Ebenfalls im Rahmen der VST-Reform sollte auch der <strong>Beteiligungsabzug<\/strong> f\u00fcr Fremdfinanzierungsaktivit\u00e4ten angepasst werden. Die VST-Reform inkl. Optimierung des Beteiligungsabzugs stellen f\u00fcr unseren Wirtschaftsstandort eine Chance dar, international an Attraktivit\u00e4t zuzulegen. SwissHoldings misst diesem Projekt deshalb klar Priorit\u00e4t bei. Zusch\u00fcsse, die der Aufrechterhaltung des Gesch\u00e4ftsbetriebs und dem Erhalt von Arbeitspl\u00e4tzen dienen, sollten nicht unn\u00f6tig besteuert werden. Die <strong>Abschaffung der Emissionsabgabe<\/strong> ist aktuell im St\u00e4nderat sistiert (<a href=\"https:\/\/swissholdings.ch\/weg-mit-der-emissionsabgabe-keine-steuern-auf-verlustabsorbierendem-eigenkapital\/\" target=\"_blank\" rel=\"noopener noreferrer\">vgl. Editorial Emissionsabgabe<\/a>). SwissHoldings erhofft sich, dass der Bericht einen neuen Impuls ausl\u00f6st und das Gesch\u00e4ft deblockiert wird. Zur Absorbierung der Corona-bedingten Verluste helfen nur Eigenkapitalzusch\u00fcsse, die aktuell, soweit die Freigrenze von einer Million Franken \u00fcberschritten ist, einer Steuer von einem Prozent unterliegen.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Vorausschauendes Planen f\u00fcr die Zeit nach Corona<\/strong><\/p>\n<p>Die Schweiz konzentrierte sich im vergangenen Jahr bisher darauf, die Bev\u00f6lkerung vor dem Corona-Virus zu sch\u00fctzen und die negativen wirtschaftlichen Effekte aufgrund von Lockdowns etc. abzufedern. Diese Priorit\u00e4tensetzung ist zweifelslos richtig. Dennoch m\u00fcssen bereits heute die Weichen f\u00fcr einen zuk\u00fcnftigen Schuldenabbau gestellt werden. Steuerreformen, die unseren Wirtschaftsstandort st\u00e4rken und ein g\u00fcnstiges Kosten-Nutzen-Verh\u00e4ltnis aufweisen, werden hierf\u00fcr einen wichtigen Beitrag leisten (<a href=\"https:\/\/swissholdings.ch\/steuerpolitische-prioritaeten-nach-corona-fokus-auf-wirtschaftswachstum-wettbewerbsfaehigkeit-und-steuereinnahmen\/\">vgl. Editorial Steuerstandort<\/a>). Die im Bericht der Expertengruppe empfohlenen Massnahmen sind daher wichtige Schritte, um dieses Ziel zu erreichen.<\/p>\n<p>&nbsp;<\/p>\n<p>Weitere Informationen zur Verrechnungssteuer finden Sie im SwissHoldings <a href=\"https:\/\/swissholdings.ch\/dossier-verrechnungssteuerreform\/\" target=\"_blank\" rel=\"noopener noreferrer\">Dossier Verrechnungssteuerreform<\/a>.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>F\u00fcr Ausk\u00fcnfte:<\/strong><br \/>\nDr. Gabriel Rumo \u2502 Direktor \u2502 079 712 20 20<br \/>\nMartin Hess \u2502 Leiter Steuern \u2502078 805 04 95<br \/>\nPascal Nussbaum \u2502 Leiter Kommunikation &amp; Public Affairs \u2502 079 798 52 40<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Die politische Debatte wird aktuell von den Auswirkungen der Corona-Pandemie bzw. von den zu deren Eind\u00e4mmung ergriffenen Massnahmen dominiert. Dieser Fokus ist richtig. Dennoch muss die Schweiz den Blick bereits heute wieder nach vorne richten. Steuerreformen, die unseren Wirtschafsstandort st\u00e4rken, haben angesichts der konjunkturellen Lage und der Schuldensituation noch einmal an Bedeutung und Dringlichkeit gewonnen. &hellip;<\/p>\n","protected":false},"author":4,"featured_media":100002453,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[68,4,69],"tags":[],"class_list":["post-100002456","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nationales-steuerrecht","category-medienmitteilungen","category-verrechnungssteuerreform"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>SwissHoldings begr\u00fcsst Expertenbericht Steuerstandort Schweiz - Swissholdings EN<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/swissholdings.ch\/en\/swissholdings-begruesst-expertenbericht-steuerstandort-schweiz-4\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"SwissHoldings begr\u00fcsst Expertenbericht Steuerstandort Schweiz - Swissholdings EN\" \/>\n<meta property=\"og:description\" content=\"Die politische Debatte wird aktuell von den Auswirkungen der Corona-Pandemie bzw. von den zu deren Eind\u00e4mmung ergriffenen Massnahmen dominiert. Dieser Fokus ist richtig. Dennoch muss die Schweiz den Blick bereits heute wieder nach vorne richten. Steuerreformen, die unseren Wirtschafsstandort st\u00e4rken, haben angesichts der konjunkturellen Lage und der Schuldensituation noch einmal an Bedeutung und Dringlichkeit gewonnen. &hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/swissholdings.ch\/en\/swissholdings-begruesst-expertenbericht-steuerstandort-schweiz-4\/\" \/>\n<meta property=\"og:site_name\" content=\"Swissholdings EN\" \/>\n<meta property=\"article:published_time\" content=\"2021-02-04T09:12:34+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/swissholdings.ch\/en\/wp-content\/uploads\/sites\/4\/2021\/02\/Steuern-Swissholding.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1\" \/>\n\t<meta property=\"og:image:height\" content=\"1\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Pascal Nussbaum\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Pascal Nussbaum\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/swissholdings.ch\/en\/swissholdings-begruesst-expertenbericht-steuerstandort-schweiz-4\/\",\"url\":\"https:\/\/swissholdings.ch\/en\/swissholdings-begruesst-expertenbericht-steuerstandort-schweiz-4\/\",\"name\":\"SwissHoldings begr\u00fcsst Expertenbericht Steuerstandort Schweiz - Swissholdings EN\",\"isPartOf\":{\"@id\":\"https:\/\/swissholdings.ch\/en\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/swissholdings.ch\/en\/swissholdings-begruesst-expertenbericht-steuerstandort-schweiz-4\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/swissholdings.ch\/en\/swissholdings-begruesst-expertenbericht-steuerstandort-schweiz-4\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/swissholdings.ch\/en\/wp-content\/uploads\/sites\/4\/2021\/02\/Steuern-Swissholding.jpg\",\"datePublished\":\"2021-02-04T09:12:34+00:00\",\"author\":{\"@id\":\"https:\/\/swissholdings.ch\/en\/#\/schema\/person\/f9ff363c9d3fafcfac26fa22fef45743\"},\"breadcrumb\":{\"@id\":\"https:\/\/swissholdings.ch\/en\/swissholdings-begruesst-expertenbericht-steuerstandort-schweiz-4\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/swissholdings.ch\/en\/swissholdings-begruesst-expertenbericht-steuerstandort-schweiz-4\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/swissholdings.ch\/en\/swissholdings-begruesst-expertenbericht-steuerstandort-schweiz-4\/#primaryimage\",\"url\":\"https:\/\/swissholdings.ch\/en\/wp-content\/uploads\/sites\/4\/2021\/02\/Steuern-Swissholding.jpg\",\"contentUrl\":\"https:\/\/swissholdings.ch\/en\/wp-content\/uploads\/sites\/4\/2021\/02\/Steuern-Swissholding.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/swissholdings.ch\/en\/swissholdings-begruesst-expertenbericht-steuerstandort-schweiz-4\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/swissholdings.ch\/en\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"SwissHoldings begr\u00fcsst Expertenbericht Steuerstandort Schweiz\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/swissholdings.ch\/en\/#website\",\"url\":\"https:\/\/swissholdings.ch\/en\/\",\"name\":\"Swissholdings EN\",\"description\":\"Federation of Industrial and Service groups in Switzerland\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/swissholdings.ch\/en\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/swissholdings.ch\/en\/#\/schema\/person\/f9ff363c9d3fafcfac26fa22fef45743\",\"name\":\"Pascal Nussbaum\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/swissholdings.ch\/en\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/664120f276d22cf6fb7f7fd5f48b7b96?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/664120f276d22cf6fb7f7fd5f48b7b96?s=96&d=mm&r=g\",\"caption\":\"Pascal Nussbaum\"},\"url\":\"https:\/\/swissholdings.ch\/en\/author\/nussbaum\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"SwissHoldings begr\u00fcsst Expertenbericht Steuerstandort Schweiz - Swissholdings EN","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/swissholdings.ch\/en\/swissholdings-begruesst-expertenbericht-steuerstandort-schweiz-4\/","og_locale":"en_US","og_type":"article","og_title":"SwissHoldings begr\u00fcsst Expertenbericht Steuerstandort Schweiz - Swissholdings EN","og_description":"Die politische Debatte wird aktuell von den Auswirkungen der Corona-Pandemie bzw. von den zu deren Eind\u00e4mmung ergriffenen Massnahmen dominiert. Dieser Fokus ist richtig. Dennoch muss die Schweiz den Blick bereits heute wieder nach vorne richten. Steuerreformen, die unseren Wirtschafsstandort st\u00e4rken, haben angesichts der konjunkturellen Lage und der Schuldensituation noch einmal an Bedeutung und Dringlichkeit gewonnen. &hellip;","og_url":"https:\/\/swissholdings.ch\/en\/swissholdings-begruesst-expertenbericht-steuerstandort-schweiz-4\/","og_site_name":"Swissholdings EN","article_published_time":"2021-02-04T09:12:34+00:00","og_image":[{"url":"https:\/\/swissholdings.ch\/en\/wp-content\/uploads\/sites\/4\/2021\/02\/Steuern-Swissholding.jpg","width":1,"height":1,"type":"image\/jpeg"}],"author":"Pascal Nussbaum","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Pascal Nussbaum","Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/swissholdings.ch\/en\/swissholdings-begruesst-expertenbericht-steuerstandort-schweiz-4\/","url":"https:\/\/swissholdings.ch\/en\/swissholdings-begruesst-expertenbericht-steuerstandort-schweiz-4\/","name":"SwissHoldings begr\u00fcsst Expertenbericht Steuerstandort Schweiz - Swissholdings EN","isPartOf":{"@id":"https:\/\/swissholdings.ch\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/swissholdings.ch\/en\/swissholdings-begruesst-expertenbericht-steuerstandort-schweiz-4\/#primaryimage"},"image":{"@id":"https:\/\/swissholdings.ch\/en\/swissholdings-begruesst-expertenbericht-steuerstandort-schweiz-4\/#primaryimage"},"thumbnailUrl":"https:\/\/swissholdings.ch\/en\/wp-content\/uploads\/sites\/4\/2021\/02\/Steuern-Swissholding.jpg","datePublished":"2021-02-04T09:12:34+00:00","author":{"@id":"https:\/\/swissholdings.ch\/en\/#\/schema\/person\/f9ff363c9d3fafcfac26fa22fef45743"},"breadcrumb":{"@id":"https:\/\/swissholdings.ch\/en\/swissholdings-begruesst-expertenbericht-steuerstandort-schweiz-4\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/swissholdings.ch\/en\/swissholdings-begruesst-expertenbericht-steuerstandort-schweiz-4\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/swissholdings.ch\/en\/swissholdings-begruesst-expertenbericht-steuerstandort-schweiz-4\/#primaryimage","url":"https:\/\/swissholdings.ch\/en\/wp-content\/uploads\/sites\/4\/2021\/02\/Steuern-Swissholding.jpg","contentUrl":"https:\/\/swissholdings.ch\/en\/wp-content\/uploads\/sites\/4\/2021\/02\/Steuern-Swissholding.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/swissholdings.ch\/en\/swissholdings-begruesst-expertenbericht-steuerstandort-schweiz-4\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/swissholdings.ch\/en\/"},{"@type":"ListItem","position":2,"name":"SwissHoldings begr\u00fcsst Expertenbericht Steuerstandort Schweiz"}]},{"@type":"WebSite","@id":"https:\/\/swissholdings.ch\/en\/#website","url":"https:\/\/swissholdings.ch\/en\/","name":"Swissholdings EN","description":"Federation of Industrial and Service groups in Switzerland","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/swissholdings.ch\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Person","@id":"https:\/\/swissholdings.ch\/en\/#\/schema\/person\/f9ff363c9d3fafcfac26fa22fef45743","name":"Pascal Nussbaum","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/swissholdings.ch\/en\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/664120f276d22cf6fb7f7fd5f48b7b96?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/664120f276d22cf6fb7f7fd5f48b7b96?s=96&d=mm&r=g","caption":"Pascal Nussbaum"},"url":"https:\/\/swissholdings.ch\/en\/author\/nussbaum\/"}]}},"_links":{"self":[{"href":"https:\/\/swissholdings.ch\/en\/wp-json\/wp\/v2\/posts\/100002456","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/swissholdings.ch\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/swissholdings.ch\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/swissholdings.ch\/en\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/swissholdings.ch\/en\/wp-json\/wp\/v2\/comments?post=100002456"}],"version-history":[{"count":0,"href":"https:\/\/swissholdings.ch\/en\/wp-json\/wp\/v2\/posts\/100002456\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/swissholdings.ch\/en\/wp-json\/wp\/v2\/media\/100002453"}],"wp:attachment":[{"href":"https:\/\/swissholdings.ch\/en\/wp-json\/wp\/v2\/media?parent=100002456"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/swissholdings.ch\/en\/wp-json\/wp\/v2\/categories?post=100002456"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/swissholdings.ch\/en\/wp-json\/wp\/v2\/tags?post=100002456"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}