{"id":100002109,"date":"2020-06-19T07:51:53","date_gmt":"2020-06-19T05:51:53","guid":{"rendered":"https:\/\/swissholdings.ch\/en\/parlament-verabschiedet-alternative-zur-unternehmens-verantwortungs-initiative\/"},"modified":"2020-06-19T07:51:53","modified_gmt":"2020-06-19T05:51:53","slug":"parlament-verabschiedet-alternative-zur-unternehmens-verantwortungs-initiative","status":"publish","type":"post","link":"https:\/\/swissholdings.ch\/en\/parlament-verabschiedet-alternative-zur-unternehmens-verantwortungs-initiative\/","title":{"rendered":"Parlament verabschiedet Alternative zur Unternehmens-Verantwortungs-Initiative"},"content":{"rendered":"<p><strong>Nach dem Bundesrat und dem St\u00e4nderat empfiehlt auch der Nationalrat die extreme Unternehmens-Verantwortungs-Initiative zur Ablehnung. Das Parlament heute in der Schlussabstimmung einem indirekten Gegenvorschlag zugestimmt. Dieser schafft strengere Vorgaben f\u00fcr Unternehmen zur Respektierung von Menschenrechten und Umwelt in der Lieferkette, sch\u00fctzt die Unternehmen aber vor missbr\u00e4uchlichen und erpresserischen Klagen. Die Wirtschaftsverb\u00e4nde unterst\u00fctzen diesen Kompromiss, weil dieser auf international bew\u00e4hrte L\u00f6sungen setzt und nicht zu einem Schweizer Alleingang f\u00fchrt.<\/strong><br \/>\nBundesrat und Parlament lehnen die extreme Unternehmens-Verantwortungs-Initiative ab und empfehlen den Stimmberechtigten im Falle einer Volksabstimmung ein Nein. Die Wirtschaftsverb\u00e4nde freuen sich \u00fcber dieses wichtige Signal, denn die Volksinitiative \u00abf\u00fcr verantwortungsvolle Unternehmen\u00bb verfehlt ihr Ziel und h\u00e4tte weitreichende soziale, \u00f6konomische, rechtliche und staatspolitische Probleme zur Folge.<\/p>\n<p><strong>Wirtschaft unterst\u00fctzt den Gegenvorschlag <\/strong><br \/>\nDie Wirtschaftsverb\u00e4nde unterst\u00fctzen den Kompromissvorschlag, auch wenn dieser weit geht und die Unternehmen vor grosse Herausforderungen stellen wird. Entscheidend f\u00fcr diese Position ist, dass der Gegenvorschlag zukunftsgerichtet und spezifisch auf die tats\u00e4chlichen Herausforderungen in den weltweiten M\u00e4rkten ausgerichtet ist. Der heute beschlossene Nachvollzug der EU-Rechenschaftsregeln sowie die Einf\u00fchrung der spezifischen Sorgfaltspflichten im Bereich der Kinderarbeit und Konfliktmineralien schaffen die Basis f\u00fcr eine zielf\u00fchrende und sachgerechte Regulierung und r\u00fccken die Schweiz international in die Top drei der am weitesten regulierten L\u00e4nder im Bereich der Unternehmensverantwortung.<\/p>\n<p>Das Parlament hat in den letzten zwei Jahren nach dem richtigen Weg gesucht, um das Anliegen der Volksinitiative aufzunehmen, ohne \u00fcber das Ziel hinauszuschiessen. Der heute verabschiedete Gegenvorschlag ist die Antwort auf diese Frage: Der Gegenvorschlag schafft mehr Verbindlichkeit f\u00fcr die Unternehmen, ohne diese missbr\u00e4uchlichen Klagen auszuliefern. Zudem erm\u00f6glicht der Vorschlag eine im Rahmen k\u00fcnftiger Gesetzesrevisionen laufende Weiterentwicklung entlang der internationalen Entwicklungen.<\/p>\n<p><strong>Gelebte Antwort der Unternehmen<\/strong><br \/>\nDie Schweizer Wirtschaft mit ihren zahlreichen Unternehmen blickt stolz auf die Effekte ihrer internationalen T\u00e4tigkeit, darunter die Schaffung von Arbeitspl\u00e4tzen, die F\u00f6rderung von Bildung und den Ausbau von Infrastrukturen \u2013 gerade auch in wirtschaftlich wenig entwickelten L\u00e4ndern. Unsere Unternehmen sind sich ihrer Verantwortung bewusst und nehmen diese weltweit auch im zum Teil herausfordernden Umfeld wahr. Wir sind bereit, in der Abstimmung aufzuzeigen, wie unsere Unternehmen Verantwortung leben und dass die Initiative verfehlt ist.<\/p>\n<p><strong>F\u00fcr Ausk\u00fcnfte:\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0<\/strong><br \/>\nDenise Laufer\u2502Mitglied der Gesch\u00e4ftsleitung\u2502076 407 02 48<br \/>\nPascal Nussbaum\u2502Leiter Kommunikation &amp; Public Affairs\u2502079 798 52 40<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Nach dem Bundesrat und dem St\u00e4nderat empfiehlt auch der Nationalrat die extreme Unternehmens-Verantwortungs-Initiative zur Ablehnung. Das Parlament heute in der Schlussabstimmung einem indirekten Gegenvorschlag zugestimmt. Dieser schafft strengere Vorgaben f\u00fcr Unternehmen zur Respektierung von Menschenrechten und Umwelt in der Lieferkette, sch\u00fctzt die Unternehmen aber vor missbr\u00e4uchlichen und erpresserischen Klagen. Die Wirtschaftsverb\u00e4nde unterst\u00fctzen diesen Kompromiss, weil &hellip;<\/p>\n","protected":false},"author":4,"featured_media":100002110,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[63,50,4,9],"tags":[],"class_list":["post-100002109","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-corporate-social-responsibility","category-konzern-initiative","category-medienmitteilungen","category-handels-und-investitionspolitik"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Parlament verabschiedet Alternative zur Unternehmens-Verantwortungs-Initiative - Swissholdings EN %<\/title>\n<meta name=\"description\" content=\"Gegenvorschlag zur Unternehmens-Verantwortungs-Initiative vom Parlament heute verabschiedet.Die Wirtschaft begr\u00fcsst diesen Schritt.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/swissholdings.ch\/en\/parlament-verabschiedet-alternative-zur-unternehmens-verantwortungs-initiative\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Parlament verabschiedet Alternative zur Unternehmens-Verantwortungs-Initiative - Swissholdings EN %\" \/>\n<meta property=\"og:description\" content=\"Gegenvorschlag zur Unternehmens-Verantwortungs-Initiative vom Parlament heute verabschiedet.Die Wirtschaft begr\u00fcsst diesen Schritt.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/swissholdings.ch\/en\/parlament-verabschiedet-alternative-zur-unternehmens-verantwortungs-initiative\/\" \/>\n<meta property=\"og:site_name\" content=\"Swissholdings EN\" \/>\n<meta property=\"article:published_time\" content=\"2020-06-19T05:51:53+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/swissholdings.ch\/en\/wp-content\/uploads\/sites\/4\/2020\/07\/Direktinvestitionen-2.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1\" \/>\n\t<meta property=\"og:image:height\" content=\"1\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Pascal Nussbaum\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Pascal Nussbaum\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/swissholdings.ch\/en\/parlament-verabschiedet-alternative-zur-unternehmens-verantwortungs-initiative\/\",\"url\":\"https:\/\/swissholdings.ch\/en\/parlament-verabschiedet-alternative-zur-unternehmens-verantwortungs-initiative\/\",\"name\":\"Parlament verabschiedet Alternative zur Unternehmens-Verantwortungs-Initiative - Swissholdings EN %\",\"isPartOf\":{\"@id\":\"https:\/\/swissholdings.ch\/en\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/swissholdings.ch\/en\/parlament-verabschiedet-alternative-zur-unternehmens-verantwortungs-initiative\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/swissholdings.ch\/en\/parlament-verabschiedet-alternative-zur-unternehmens-verantwortungs-initiative\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/swissholdings.ch\/en\/wp-content\/uploads\/sites\/4\/2020\/07\/Direktinvestitionen-2.jpg\",\"datePublished\":\"2020-06-19T05:51:53+00:00\",\"author\":{\"@id\":\"https:\/\/swissholdings.ch\/en\/#\/schema\/person\/f9ff363c9d3fafcfac26fa22fef45743\"},\"description\":\"Gegenvorschlag zur Unternehmens-Verantwortungs-Initiative vom Parlament heute verabschiedet.Die Wirtschaft begr\u00fcsst diesen Schritt.\",\"breadcrumb\":{\"@id\":\"https:\/\/swissholdings.ch\/en\/parlament-verabschiedet-alternative-zur-unternehmens-verantwortungs-initiative\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/swissholdings.ch\/en\/parlament-verabschiedet-alternative-zur-unternehmens-verantwortungs-initiative\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/swissholdings.ch\/en\/parlament-verabschiedet-alternative-zur-unternehmens-verantwortungs-initiative\/#primaryimage\",\"url\":\"https:\/\/swissholdings.ch\/en\/wp-content\/uploads\/sites\/4\/2020\/07\/Direktinvestitionen-2.jpg\",\"contentUrl\":\"https:\/\/swissholdings.ch\/en\/wp-content\/uploads\/sites\/4\/2020\/07\/Direktinvestitionen-2.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/swissholdings.ch\/en\/parlament-verabschiedet-alternative-zur-unternehmens-verantwortungs-initiative\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/swissholdings.ch\/en\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Parlament verabschiedet Alternative zur Unternehmens-Verantwortungs-Initiative\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/swissholdings.ch\/en\/#website\",\"url\":\"https:\/\/swissholdings.ch\/en\/\",\"name\":\"Swissholdings EN\",\"description\":\"Federation of Industrial and Service groups in Switzerland\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/swissholdings.ch\/en\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/swissholdings.ch\/en\/#\/schema\/person\/f9ff363c9d3fafcfac26fa22fef45743\",\"name\":\"Pascal Nussbaum\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/swissholdings.ch\/en\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/664120f276d22cf6fb7f7fd5f48b7b96?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/664120f276d22cf6fb7f7fd5f48b7b96?s=96&d=mm&r=g\",\"caption\":\"Pascal Nussbaum\"},\"url\":\"https:\/\/swissholdings.ch\/en\/author\/nussbaum\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Parlament verabschiedet Alternative zur Unternehmens-Verantwortungs-Initiative - Swissholdings EN %","description":"Gegenvorschlag zur Unternehmens-Verantwortungs-Initiative vom Parlament heute verabschiedet.Die Wirtschaft begr\u00fcsst diesen Schritt.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/swissholdings.ch\/en\/parlament-verabschiedet-alternative-zur-unternehmens-verantwortungs-initiative\/","og_locale":"en_US","og_type":"article","og_title":"Parlament verabschiedet Alternative zur Unternehmens-Verantwortungs-Initiative - Swissholdings EN %","og_description":"Gegenvorschlag zur Unternehmens-Verantwortungs-Initiative vom Parlament heute verabschiedet.Die Wirtschaft begr\u00fcsst diesen Schritt.","og_url":"https:\/\/swissholdings.ch\/en\/parlament-verabschiedet-alternative-zur-unternehmens-verantwortungs-initiative\/","og_site_name":"Swissholdings EN","article_published_time":"2020-06-19T05:51:53+00:00","og_image":[{"url":"https:\/\/swissholdings.ch\/en\/wp-content\/uploads\/sites\/4\/2020\/07\/Direktinvestitionen-2.jpg","width":1,"height":1,"type":"image\/jpeg"}],"author":"Pascal Nussbaum","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Pascal Nussbaum","Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/swissholdings.ch\/en\/parlament-verabschiedet-alternative-zur-unternehmens-verantwortungs-initiative\/","url":"https:\/\/swissholdings.ch\/en\/parlament-verabschiedet-alternative-zur-unternehmens-verantwortungs-initiative\/","name":"Parlament verabschiedet Alternative zur Unternehmens-Verantwortungs-Initiative - Swissholdings EN %","isPartOf":{"@id":"https:\/\/swissholdings.ch\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/swissholdings.ch\/en\/parlament-verabschiedet-alternative-zur-unternehmens-verantwortungs-initiative\/#primaryimage"},"image":{"@id":"https:\/\/swissholdings.ch\/en\/parlament-verabschiedet-alternative-zur-unternehmens-verantwortungs-initiative\/#primaryimage"},"thumbnailUrl":"https:\/\/swissholdings.ch\/en\/wp-content\/uploads\/sites\/4\/2020\/07\/Direktinvestitionen-2.jpg","datePublished":"2020-06-19T05:51:53+00:00","author":{"@id":"https:\/\/swissholdings.ch\/en\/#\/schema\/person\/f9ff363c9d3fafcfac26fa22fef45743"},"description":"Gegenvorschlag zur Unternehmens-Verantwortungs-Initiative vom Parlament heute verabschiedet.Die Wirtschaft begr\u00fcsst diesen Schritt.","breadcrumb":{"@id":"https:\/\/swissholdings.ch\/en\/parlament-verabschiedet-alternative-zur-unternehmens-verantwortungs-initiative\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/swissholdings.ch\/en\/parlament-verabschiedet-alternative-zur-unternehmens-verantwortungs-initiative\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/swissholdings.ch\/en\/parlament-verabschiedet-alternative-zur-unternehmens-verantwortungs-initiative\/#primaryimage","url":"https:\/\/swissholdings.ch\/en\/wp-content\/uploads\/sites\/4\/2020\/07\/Direktinvestitionen-2.jpg","contentUrl":"https:\/\/swissholdings.ch\/en\/wp-content\/uploads\/sites\/4\/2020\/07\/Direktinvestitionen-2.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/swissholdings.ch\/en\/parlament-verabschiedet-alternative-zur-unternehmens-verantwortungs-initiative\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/swissholdings.ch\/en\/"},{"@type":"ListItem","position":2,"name":"Parlament verabschiedet Alternative zur Unternehmens-Verantwortungs-Initiative"}]},{"@type":"WebSite","@id":"https:\/\/swissholdings.ch\/en\/#website","url":"https:\/\/swissholdings.ch\/en\/","name":"Swissholdings EN","description":"Federation of Industrial and Service groups in Switzerland","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/swissholdings.ch\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Person","@id":"https:\/\/swissholdings.ch\/en\/#\/schema\/person\/f9ff363c9d3fafcfac26fa22fef45743","name":"Pascal Nussbaum","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/swissholdings.ch\/en\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/664120f276d22cf6fb7f7fd5f48b7b96?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/664120f276d22cf6fb7f7fd5f48b7b96?s=96&d=mm&r=g","caption":"Pascal Nussbaum"},"url":"https:\/\/swissholdings.ch\/en\/author\/nussbaum\/"}]}},"_links":{"self":[{"href":"https:\/\/swissholdings.ch\/en\/wp-json\/wp\/v2\/posts\/100002109","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/swissholdings.ch\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/swissholdings.ch\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/swissholdings.ch\/en\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/swissholdings.ch\/en\/wp-json\/wp\/v2\/comments?post=100002109"}],"version-history":[{"count":0,"href":"https:\/\/swissholdings.ch\/en\/wp-json\/wp\/v2\/posts\/100002109\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/swissholdings.ch\/en\/wp-json\/wp\/v2\/media\/100002110"}],"wp:attachment":[{"href":"https:\/\/swissholdings.ch\/en\/wp-json\/wp\/v2\/media?parent=100002109"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/swissholdings.ch\/en\/wp-json\/wp\/v2\/categories?post=100002109"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/swissholdings.ch\/en\/wp-json\/wp\/v2\/tags?post=100002109"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}